{"id":5252,"count":21,"description":"","link":"https:\/\/blogs.qut.edu.au\/gone-global\/category\/europe\/italy\/","name":"Italy","slug":"italy","taxonomy":"category","parent":5246,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Italy Archives - QUT Gone Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.qut.edu.au\/gone-global\/tag\/italy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italy Archives - QUT Gone Global\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.qut.edu.au\/gone-global\/tag\/italy\/\" \/>\n<meta property=\"og:site_name\" content=\"QUT Gone Global\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/tag\\\/italy\\\/\",\"url\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/tag\\\/italy\\\/\",\"name\":\"Italy Archives - QUT Gone Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/tag\\\/italy\\\/#breadcrumb\"},\"inLanguage\":\"en-AU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/tag\\\/italy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/#website\",\"url\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/\",\"name\":\"QUT Gone Global\",\"description\":\"QUT students studying abroad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Italy Archives - QUT Gone Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.qut.edu.au\/gone-global\/tag\/italy\/","og_locale":"en_US","og_type":"article","og_title":"Italy Archives - QUT Gone Global","og_url":"https:\/\/blogs.qut.edu.au\/gone-global\/tag\/italy\/","og_site_name":"QUT Gone Global","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.qut.edu.au\/gone-global\/tag\/italy\/","url":"https:\/\/blogs.qut.edu.au\/gone-global\/tag\/italy\/","name":"Italy Archives - QUT Gone Global","isPartOf":{"@id":"https:\/\/blogs.qut.edu.au\/gone-global\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.qut.edu.au\/gone-global\/tag\/italy\/#breadcrumb"},"inLanguage":"en-AU"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.qut.edu.au\/gone-global\/tag\/italy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.qut.edu.au\/gone-global\/"},{"@type":"ListItem","position":2,"name":"Italy"}]},{"@type":"WebSite","@id":"https:\/\/blogs.qut.edu.au\/gone-global\/#website","url":"https:\/\/blogs.qut.edu.au\/gone-global\/","name":"QUT Gone Global","description":"QUT students studying abroad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.qut.edu.au\/gone-global\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"}]}},"_links":{"self":[{"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/categories\/5252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/categories\/5246"}],"wp:post_type":[{"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/posts?categories=5252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}