{"id":5251,"count":8,"description":"","link":"https:\/\/blogs.qut.edu.au\/gone-global\/category\/europe\/ireland\/","name":"Ireland","slug":"ireland","taxonomy":"category","parent":5246,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QUT Gone Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:site_name\" content=\"QUT Gone Global\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":null,\"url\":\"\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/#website\"},\"inLanguage\":\"en-AU\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/#website\",\"url\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/\",\"name\":\"QUT Gone Global\",\"description\":\"QUT students studying abroad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.qut.edu.au\\\/gone-global\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QUT Gone Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_site_name":"QUT Gone Global","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":null,"url":"","name":"","isPartOf":{"@id":"https:\/\/blogs.qut.edu.au\/gone-global\/#website"},"inLanguage":"en-AU"},{"@type":"WebSite","@id":"https:\/\/blogs.qut.edu.au\/gone-global\/#website","url":"https:\/\/blogs.qut.edu.au\/gone-global\/","name":"QUT Gone Global","description":"QUT students studying abroad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.qut.edu.au\/gone-global\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"}]}},"_links":{"self":[{"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/categories\/5251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/categories\/5246"}],"wp:post_type":[{"href":"https:\/\/blogs.qut.edu.au\/gone-global\/wp-json\/wp\/v2\/posts?categories=5251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}